{"id":1074665,"date":"2023-03-17T16:59:49","date_gmt":"2023-03-17T09:59:49","guid":{"rendered":"https:\/\/www.dusit.ac.th\/home\/?p=1074665"},"modified":"2023-03-24T08:57:01","modified_gmt":"2023-03-24T01:57:01","slug":"%e0%b8%84%e0%b8%b3%e0%b8%9b%e0%b8%a3%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2-%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%84%e0%b8%a3%e0%b8%b8%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b8%a1%e0%b8%ab","status":"publish","type":"post","link":"https:\/\/www.dusit.ac.th\/home\/2023\/1074665.html","title":{"rendered":"\u0e1d\u0e48\u0e32\u0e22\u0e07\u0e32\u0e19\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e04\u0e13\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 4 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32"},"content":{"rendered":"<p>\u0e1d\u0e48\u0e32\u0e22\u0e07\u0e32\u0e19\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e04\u0e13\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 4 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c SDU Wellness Center \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e35\u0e13\u0e31\u0e10 \u0e2a\u0e01\u0e38\u0e25\u0e2b\u0e2d\u0e21 \u0e04\u0e13\u0e1a\u0e14\u0e35 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e31\u0e29\u0e0f\u0e32 \u0e1e\u0e25\u0e2d\u0e22\u0e42\u0e2a\u0e20\u0e13 \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e23\u0e31\u0e15\u0e19\u0e32\u0e1e\u0e23 \u0e2b\u0e25\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e07\u0e32\u0e19\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e20\u0e39\u0e23\u0e34\u0e40\u0e14\u0e0a \u0e1e\u0e32\u0e2b\u0e38\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2a\u0e32\u0e02\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e04\u0e13\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28\u0e27\u0e31\u0e19\u0e1e\u0e38\u0e18\u0e17\u0e35\u0e48 15 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2566 \u0e40\u0e27\u0e25\u0e32 9.30 &#8211; 12.00 \u0e19. \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 434 \u0e2d\u0e32\u0e04\u0e32\u0e23 4 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>\u0e1d\u0e48\u0e32\u0e22\u0e07\u0e32\u0e19\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e04\u0e13\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 4 \u0e2a\u0e32\u0e02\u0e32\u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e13 \u0e28\u0e39\u0e19\u0e22\u0e4c SDU Wellness Center \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e35\u0e13\u0e31\u0e10 \u0e2a\u0e01\u0e38\u0e25\u0e2b\u0e2d\u0e21 \u0e04\u0e13\u0e1a\u0e14\u0e35 \u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e31\u0e29\u0e0f\u0e32 \u0e1e\u0e25\u0e2d\u0e22\u0e42\u0e2a\u0e20\u0e13 \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e04\u0e23\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e23\u0e31\u0e15\u0e19\u0e32\u0e1e\u0e23 \u0e2b\u0e25\u0e27\u0e07\u0e41\u0e01\u0e49\u0e27 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1074666,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1074665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 Suan Dusit University","distributor_original_site_url":"https:\/\/www.dusit.ac.th\/home","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/1074665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/comments?post=1074665"}],"version-history":[{"count":2,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/1074665\/revisions"}],"predecessor-version":[{"id":1077383,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/1074665\/revisions\/1077383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/media\/1074666"}],"wp:attachment":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/media?parent=1074665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/categories?post=1074665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/tags?post=1074665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}