{"id":1389414,"date":"2024-12-04T12:56:00","date_gmt":"2024-12-04T05:56:00","guid":{"rendered":"https:\/\/www.dusit.ac.th\/home\/?p=1389414"},"modified":"2024-12-04T12:56:16","modified_gmt":"2024-12-04T05:56:16","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a7%e0%b8%b4%e0%b8%88%e0%b8%b1%e0%b8%a2-%e0%b8%99%e0%b8%a7%e0%b8%b1","status":"publish","type":"post","link":"https:\/\/www.dusit.ac.th\/home\/2024\/1389414.html","title":{"rendered":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 BCGs"},"content":{"rendered":"<p>\u0e1c\u0e28.\u0e14\u0e23.\u0e08\u0e34\u0e23\u0e32\u0e19\u0e38\u0e0a \u0e42\u0e2a\u0e20\u0e32 \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e28.\u0e14\u0e23.\u0e16\u0e34\u0e23\u0e1e\u0e23 \u0e41\u0e2a\u0e07\u0e1e\u0e34\u0e23\u0e38\u0e13 \u0e14\u0e23.\u0e13\u0e31\u0e0a\u0e0a\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e07\u0e28\u0e4c \u0e2d.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e23\u0e31\u0e15\u0e19\u0e2a\u0e19\u0e18\u0e34 \u0e41\u0e25\u0e30 \u0e2d.\u0e08\u0e15\u0e38\u0e23\u0e14\u0e32 \u0e42\u0e20\u0e0a\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 BCGs \u0e13 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e1e\u0e22.2567<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>\u0e1c\u0e28.\u0e14\u0e23.\u0e08\u0e34\u0e23\u0e32\u0e19\u0e38\u0e0a \u0e42\u0e2a\u0e20\u0e32 \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e28.\u0e14\u0e23.\u0e16\u0e34\u0e23\u0e1e\u0e23 \u0e41\u0e2a\u0e07\u0e1e\u0e34\u0e23\u0e38\u0e13 \u0e14\u0e23.\u0e13\u0e31\u0e0a\u0e0a\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e27\u0e07\u0e28\u0e4c \u0e2d.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e23\u0e31\u0e15\u0e19\u0e2a\u0e19\u0e18\u0e34 \u0e41\u0e25\u0e30 \u0e2d.\u0e08\u0e15\u0e38\u0e23\u0e14\u0e32 \u0e42\u0e20\u0e0a\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 BCGs \u0e13 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e1e\u0e22.2567<\/p>\n","protected":false},"author":268,"featured_media":1389415,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1389414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 Suan Dusit University","distributor_original_site_url":"https:\/\/www.dusit.ac.th\/home","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/1389414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/users\/268"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/comments?post=1389414"}],"version-history":[{"count":1,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/1389414\/revisions"}],"predecessor-version":[{"id":1389416,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/1389414\/revisions\/1389416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/media\/1389415"}],"wp:attachment":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/media?parent=1389414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/categories?post=1389414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/tags?post=1389414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}