{"id":2159264,"date":"2026-09-02T10:07:21","date_gmt":"2026-09-02T03:07:21","guid":{"rendered":"https:\/\/www.dusit.ac.th\/home\/?p=2159264"},"modified":"2026-09-02T10:07:21","modified_gmt":"2026-09-02T03:07:21","slug":"%e0%b8%aa%e0%b8%b2%e0%b8%82%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%84%e0%b8%ab%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b9%82-19","status":"publish","type":"post","link":"https:\/\/www.dusit.ac.th\/home\/2026\/2159264.html","title":{"rendered":"\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e04\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e34\u0e0d\u0e08\u0e32\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 15"},"content":{"rendered":"<p>\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e04\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2d\u0e31\u0e04\u0e23\u0e1e\u0e25 \u0e44\u0e27\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e04\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e14\u0e23.\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25 \u0e2d\u0e40\u0e19\u0e01\u0e18\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e34\u0e0d\u0e08\u0e32\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 15 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e07\u0e32\u0e19\u0e41\u0e01\u0e30\u0e2a\u0e25\u0e31\u0e01\u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e07\u0e32\u0e19\u0e43\u0e1a\u0e15\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e23\u0e49\u0e2d\u0e22\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 4-6 \u0e40\u0e40\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e15\u0e49\u0e19 \u0e40\u0e40\u0e25\u0e30\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 &#8211; 27 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2568 \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19 \u0e41\u0e2a\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1a\u0e35\u0e0a \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 ngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e04\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2d\u0e31\u0e04\u0e23\u0e1e\u0e25 \u0e44\u0e27\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e04\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e14\u0e23.\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25 \u0e2d\u0e40\u0e19\u0e01\u0e18\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e34\u0e0d\u0e08\u0e32\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 15 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e07\u0e32\u0e19\u0e41\u0e01\u0e30\u0e2a\u0e25\u0e31\u0e01\u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e07\u0e32\u0e19\u0e43\u0e1a\u0e15\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e23\u0e49\u0e2d\u0e22\u0e21\u0e32\u0e25\u0e31\u0e22 \u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 4-6 \u0e40\u0e40\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e15\u0e49\u0e19 \u0e40\u0e40\u0e25\u0e30\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 &#8211; [&hellip;]<\/p>\n","protected":false},"author":26395,"featured_media":2159340,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2159264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events"],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e27\u0e19\u0e14\u0e38\u0e2a\u0e34\u0e15 Suan Dusit University","distributor_original_site_url":"https:\/\/www.dusit.ac.th\/home","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/2159264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/users\/26395"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/comments?post=2159264"}],"version-history":[{"count":1,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/2159264\/revisions"}],"predecessor-version":[{"id":2159343,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/posts\/2159264\/revisions\/2159343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/media\/2159340"}],"wp:attachment":[{"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/media?parent=2159264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/categories?post=2159264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dusit.ac.th\/home\/wp-json\/wp\/v2\/tags?post=2159264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}